{"id":8759,"date":"2025-05-30T11:51:14","date_gmt":"2025-05-30T15:51:14","guid":{"rendered":"https:\/\/loeysdietzcanada.org\/?p=8759"},"modified":"2025-05-30T11:59:55","modified_gmt":"2025-05-30T15:59:55","slug":"renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir","status":"publish","type":"post","link":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/","title":{"rendered":"Renforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8759\" class=\"elementor elementor-8759 elementor-8751\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-9059190 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9059190\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78bdcd7\" data-id=\"78bdcd7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35a9d8a elementor-widget elementor-widget-text-editor\" data-id=\"35a9d8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>\u00c0 Loeys-Dietz Canada, nous nous engageons \u00e0 \u00e0 cr\u00e9er une communaut\u00e9 solidaire et interconnect\u00e9e aux personnes, aux familles, aux cliniciens et aux chercheurs impact\u00e9s par le syndrome de Loeys-Dietz (SLD) et d\u2019autres troubles h\u00e9r\u00e9ditaires de l\u2019aorte thoracique (HTAD) connexes.<br \/><br \/>Dans cette \u00e9dition de notre bulletin, nous vous pr\u00e9sentons :<\/div><ul><li>Les <strong>\u00e9v\u00e9nements<\/strong> \u00e0 venir<\/li><li>Un nouvel <strong>article de blogue <\/strong>percutant partageant des t\u00e9moignages de patient.e.s<\/li><li>Une <strong>s\u00e9rie de livres<\/strong> \u00e9lectroniques \u00e9crits par des patients<\/li><li>Une invitation \u00e0 r\u00e9pondre au <strong>sondage aupr\u00e8s des patients et des aidants sur le co\u00fbt des maladies rares<\/strong><\/li><\/ul><div>Que vous soyez patients, aidants ou professionnels de la sant\u00e9, nous esp\u00e9rons que ces t\u00e9moignages et \u00e9v\u00e9nements favoriseront les \u00e9changes, vous apporteront des informations pr\u00e9cieuses, et vous inspireront \u00e0 offrir un soutien et des soins mieux adapt\u00e9s aux personnes touch\u00e9es par le syndrome de Loeys-Dietz.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae19158 elementor-widget elementor-widget-html\" data-id=\"ae19158\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<object data=\"https:\/\/loeysdietzcanada.org\/wp-content\/uploads\/2025\/05\/Events-Stories-and-Advocacy-for-Patients-Clinicians-Evenements-temoignages-et-plaidoyer-pour-l.pdf\" type=\"application\/pdf\" width=\"700px\" height=\"1200px\">\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c0 Loeys-Dietz Canada, nous nous engageons \u00e0 \u00e0 cr\u00e9er une communaut\u00e9 solidaire et interconnect\u00e9e aux personnes, aux familles, aux cliniciens et aux chercheurs impact\u00e9s par le syndrome de Loeys-Dietz (SLD) [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[68],"tags":[],"class_list":["post-8759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bulletins-dinformation"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u00c0 Loeys-Dietz Canada, nous nous engageons \u00e0 \u00e0 cr\u00e9er une communaut\u00e9 solidaire et interconnect\u00e9e aux personnes, aux familles, aux cliniciens et aux chercheurs impact\u00e9s par le syndrome de Loeys-Dietz (SLD) et d\u2019autres troubles h\u00e9r\u00e9ditaires de l\u2019aorte thoracique (HTAD) connexes.Dans cette \u00e9dition de notre bulletin, nous vous pr\u00e9sentons :Les \u00e9v\u00e9nements \u00e0 venirUn nouvel article de blogue\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Lindsay Parsons\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"FSLDC -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Renforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir - FSLDC\" \/>\n\t\t<meta property=\"og:description\" content=\"\u00c0 Loeys-Dietz Canada, nous nous engageons \u00e0 \u00e0 cr\u00e9er une communaut\u00e9 solidaire et interconnect\u00e9e aux personnes, aux familles, aux cliniciens et aux chercheurs impact\u00e9s par le syndrome de Loeys-Dietz (SLD) et d\u2019autres troubles h\u00e9r\u00e9ditaires de l\u2019aorte thoracique (HTAD) connexes.Dans cette \u00e9dition de notre bulletin, nous vous pr\u00e9sentons :Les \u00e9v\u00e9nements \u00e0 venirUn nouvel article de blogue\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/loeysdietzcanada.org\/wp-content\/uploads\/2022\/06\/logowhite.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/loeysdietzcanada.org\/wp-content\/uploads\/2022\/06\/logowhite.svg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"316\" \/>\n\t\t<meta property=\"og:image:height\" content=\"105\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-05-30T15:51:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-05-30T15:59:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Renforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir - FSLDC\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u00c0 Loeys-Dietz Canada, nous nous engageons \u00e0 \u00e0 cr\u00e9er une communaut\u00e9 solidaire et interconnect\u00e9e aux personnes, aux familles, aux cliniciens et aux chercheurs impact\u00e9s par le syndrome de Loeys-Dietz (SLD) et d\u2019autres troubles h\u00e9r\u00e9ditaires de l\u2019aorte thoracique (HTAD) connexes.Dans cette \u00e9dition de notre bulletin, nous vous pr\u00e9sentons :Les \u00e9v\u00e9nements \u00e0 venirUn nouvel article de blogue\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/loeysdietzcanada.org\/wp-content\/uploads\/2022\/06\/logowhite.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#blogposting\",\"name\":\"Renforcer la communaut\\u00e9 Loeys-Dietz gr\\u00e2ce \\u00e0 des t\\u00e9moignages partag\\u00e9s, des actions de plaidoyer et des \\u00e9v\\u00e9nements \\u00e0 venir - FSLDC\",\"headline\":\"Renforcer la communaut\\u00e9 Loeys-Dietz gr\\u00e2ce \\u00e0 des t\\u00e9moignages partag\\u00e9s, des actions de plaidoyer et des \\u00e9v\\u00e9nements \\u00e0 venir\",\"author\":{\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/author\\\/lindsay\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/loeysdietzcanada.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/woven-strong.png\",\"width\":768,\"height\":1196},\"datePublished\":\"2025-05-30T11:51:14-04:00\",\"dateModified\":\"2025-05-30T11:59:55-04:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#webpage\"},\"articleSection\":\"Bulletins d'information\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/category\\\/bulletins-dinformation\\\/#listItem\",\"name\":\"Bulletins d'information\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/category\\\/bulletins-dinformation\\\/#listItem\",\"position\":2,\"name\":\"Bulletins d'information\",\"item\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/category\\\/bulletins-dinformation\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#listItem\",\"name\":\"Renforcer la communaut\\u00e9 Loeys-Dietz gr\\u00e2ce \\u00e0 des t\\u00e9moignages partag\\u00e9s, des actions de plaidoyer et des \\u00e9v\\u00e9nements \\u00e0 venir\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#listItem\",\"position\":3,\"name\":\"Renforcer la communaut\\u00e9 Loeys-Dietz gr\\u00e2ce \\u00e0 des t\\u00e9moignages partag\\u00e9s, des actions de plaidoyer et des \\u00e9v\\u00e9nements \\u00e0 venir\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/category\\\/bulletins-dinformation\\\/#listItem\",\"name\":\"Bulletins d'information\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/#organization\",\"name\":\"Loeys-Dietz Syndrome Foundation Canada\",\"url\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/loeysdietzcanada.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logowhite.svg\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/author\\\/lindsay\\\/#author\",\"url\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/author\\\/lindsay\\\/\",\"name\":\"Lindsay Parsons\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a42c65b4ca576291474512c38b31d8fd6f49bf6b0639c5c8b44a3270251ff235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Lindsay Parsons\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#webpage\",\"url\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/\",\"name\":\"Renforcer la communaut\\u00e9 Loeys-Dietz gr\\u00e2ce \\u00e0 des t\\u00e9moignages partag\\u00e9s, des actions de plaidoyer et des \\u00e9v\\u00e9nements \\u00e0 venir - FSLDC\",\"description\":\"\\u00c0 Loeys-Dietz Canada, nous nous engageons \\u00e0 \\u00e0 cr\\u00e9er une communaut\\u00e9 solidaire et interconnect\\u00e9e aux personnes, aux familles, aux cliniciens et aux chercheurs impact\\u00e9s par le syndrome de Loeys-Dietz (SLD) et d\\u2019autres troubles h\\u00e9r\\u00e9ditaires de l\\u2019aorte thoracique (HTAD) connexes.Dans cette \\u00e9dition de notre bulletin, nous vous pr\\u00e9sentons :Les \\u00e9v\\u00e9nements \\u00e0 venirUn nouvel article de blogue\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/author\\\/lindsay\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/author\\\/lindsay\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/loeysdietzcanada.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/woven-strong.png\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#mainImage\",\"width\":768,\"height\":1196},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\\\/#mainImage\"},\"datePublished\":\"2025-05-30T11:51:14-04:00\",\"dateModified\":\"2025-05-30T11:59:55-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/\",\"name\":\"Loeys-Dietz Syndrome Foundation Canada\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/loeysdietzcanada.org\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Renforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir - FSLDC","description":"\u00c0 Loeys-Dietz Canada, nous nous engageons \u00e0 \u00e0 cr\u00e9er une communaut\u00e9 solidaire et interconnect\u00e9e aux personnes, aux familles, aux cliniciens et aux chercheurs impact\u00e9s par le syndrome de Loeys-Dietz (SLD) et d\u2019autres troubles h\u00e9r\u00e9ditaires de l\u2019aorte thoracique (HTAD) connexes.Dans cette \u00e9dition de notre bulletin, nous vous pr\u00e9sentons :Les \u00e9v\u00e9nements \u00e0 venirUn nouvel article de blogue","canonical_url":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#blogposting","name":"Renforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir - FSLDC","headline":"Renforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir","author":{"@id":"https:\/\/loeysdietzcanada.org\/fr\/author\/lindsay\/#author"},"publisher":{"@id":"https:\/\/loeysdietzcanada.org\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/loeysdietzcanada.org\/wp-content\/uploads\/2025\/05\/woven-strong.png","width":768,"height":1196},"datePublished":"2025-05-30T11:51:14-04:00","dateModified":"2025-05-30T11:59:55-04:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#webpage"},"isPartOf":{"@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#webpage"},"articleSection":"Bulletins d'information"},{"@type":"BreadcrumbList","@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/loeysdietzcanada.org\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/loeysdietzcanada.org\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/loeysdietzcanada.org\/fr\/category\/bulletins-dinformation\/#listItem","name":"Bulletins d'information"}},{"@type":"ListItem","@id":"https:\/\/loeysdietzcanada.org\/fr\/category\/bulletins-dinformation\/#listItem","position":2,"name":"Bulletins d'information","item":"https:\/\/loeysdietzcanada.org\/fr\/category\/bulletins-dinformation\/","nextItem":{"@type":"ListItem","@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#listItem","name":"Renforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir"},"previousItem":{"@type":"ListItem","@id":"https:\/\/loeysdietzcanada.org\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#listItem","position":3,"name":"Renforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir","previousItem":{"@type":"ListItem","@id":"https:\/\/loeysdietzcanada.org\/fr\/category\/bulletins-dinformation\/#listItem","name":"Bulletins d'information"}}]},{"@type":"Organization","@id":"https:\/\/loeysdietzcanada.org\/fr\/#organization","name":"Loeys-Dietz Syndrome Foundation Canada","url":"https:\/\/loeysdietzcanada.org\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/loeysdietzcanada.org\/wp-content\/uploads\/2022\/06\/logowhite.svg","@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#organizationLogo"},"image":{"@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/loeysdietzcanada.org\/fr\/author\/lindsay\/#author","url":"https:\/\/loeysdietzcanada.org\/fr\/author\/lindsay\/","name":"Lindsay Parsons","image":{"@type":"ImageObject","@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a42c65b4ca576291474512c38b31d8fd6f49bf6b0639c5c8b44a3270251ff235?s=96&d=mm&r=g","width":96,"height":96,"caption":"Lindsay Parsons"}},{"@type":"WebPage","@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#webpage","url":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/","name":"Renforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir - FSLDC","description":"\u00c0 Loeys-Dietz Canada, nous nous engageons \u00e0 \u00e0 cr\u00e9er une communaut\u00e9 solidaire et interconnect\u00e9e aux personnes, aux familles, aux cliniciens et aux chercheurs impact\u00e9s par le syndrome de Loeys-Dietz (SLD) et d\u2019autres troubles h\u00e9r\u00e9ditaires de l\u2019aorte thoracique (HTAD) connexes.Dans cette \u00e9dition de notre bulletin, nous vous pr\u00e9sentons :Les \u00e9v\u00e9nements \u00e0 venirUn nouvel article de blogue","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/loeysdietzcanada.org\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#breadcrumblist"},"author":{"@id":"https:\/\/loeysdietzcanada.org\/fr\/author\/lindsay\/#author"},"creator":{"@id":"https:\/\/loeysdietzcanada.org\/fr\/author\/lindsay\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/loeysdietzcanada.org\/wp-content\/uploads\/2025\/05\/woven-strong.png","@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#mainImage","width":768,"height":1196},"primaryImageOfPage":{"@id":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/#mainImage"},"datePublished":"2025-05-30T11:51:14-04:00","dateModified":"2025-05-30T11:59:55-04:00"},{"@type":"WebSite","@id":"https:\/\/loeysdietzcanada.org\/fr\/#website","url":"https:\/\/loeysdietzcanada.org\/fr\/","name":"Loeys-Dietz Syndrome Foundation Canada","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/loeysdietzcanada.org\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"FSLDC -","og:type":"article","og:title":"Renforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir - FSLDC","og:description":"\u00c0 Loeys-Dietz Canada, nous nous engageons \u00e0 \u00e0 cr\u00e9er une communaut\u00e9 solidaire et interconnect\u00e9e aux personnes, aux familles, aux cliniciens et aux chercheurs impact\u00e9s par le syndrome de Loeys-Dietz (SLD) et d\u2019autres troubles h\u00e9r\u00e9ditaires de l\u2019aorte thoracique (HTAD) connexes.Dans cette \u00e9dition de notre bulletin, nous vous pr\u00e9sentons :Les \u00e9v\u00e9nements \u00e0 venirUn nouvel article de blogue","og:url":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/","og:image":"https:\/\/loeysdietzcanada.org\/wp-content\/uploads\/2022\/06\/logowhite.svg","og:image:secure_url":"https:\/\/loeysdietzcanada.org\/wp-content\/uploads\/2022\/06\/logowhite.svg","og:image:width":316,"og:image:height":105,"article:published_time":"2025-05-30T15:51:14+00:00","article:modified_time":"2025-05-30T15:59:55+00:00","twitter:card":"summary_large_image","twitter:title":"Renforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir - FSLDC","twitter:description":"\u00c0 Loeys-Dietz Canada, nous nous engageons \u00e0 \u00e0 cr\u00e9er une communaut\u00e9 solidaire et interconnect\u00e9e aux personnes, aux familles, aux cliniciens et aux chercheurs impact\u00e9s par le syndrome de Loeys-Dietz (SLD) et d\u2019autres troubles h\u00e9r\u00e9ditaires de l\u2019aorte thoracique (HTAD) connexes.Dans cette \u00e9dition de notre bulletin, nous vous pr\u00e9sentons :Les \u00e9v\u00e9nements \u00e0 venirUn nouvel article de blogue","twitter:image":"https:\/\/loeysdietzcanada.org\/wp-content\/uploads\/2022\/06\/logowhite.svg"},"aioseo_meta_data":{"post_id":"8759","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-05-30 15:59:07","updated":"2025-06-03 20:29:51","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/loeysdietzcanada.org\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/loeysdietzcanada.org\/fr\/category\/bulletins-dinformation\/\" title=\"Bulletins d&apos;information\">Bulletins d'information<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRenforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/loeysdietzcanada.org\/fr\/"},{"label":"Bulletins d'information","link":"https:\/\/loeysdietzcanada.org\/fr\/category\/bulletins-dinformation\/"},{"label":"Renforcer la communaut\u00e9 Loeys-Dietz gr\u00e2ce \u00e0 des t\u00e9moignages partag\u00e9s, des actions de plaidoyer et des \u00e9v\u00e9nements \u00e0 venir","link":"https:\/\/loeysdietzcanada.org\/fr\/renforcer-la-communaute-loeys-dietz-grace-a-des-temoignages-partages-des-actions-de-plaidoyer-et-des-evenements-a-venir\/"}],"_links":{"self":[{"href":"https:\/\/loeysdietzcanada.org\/fr\/wp-json\/wp\/v2\/posts\/8759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loeysdietzcanada.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loeysdietzcanada.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loeysdietzcanada.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/loeysdietzcanada.org\/fr\/wp-json\/wp\/v2\/comments?post=8759"}],"version-history":[{"count":4,"href":"https:\/\/loeysdietzcanada.org\/fr\/wp-json\/wp\/v2\/posts\/8759\/revisions"}],"predecessor-version":[{"id":8763,"href":"https:\/\/loeysdietzcanada.org\/fr\/wp-json\/wp\/v2\/posts\/8759\/revisions\/8763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loeysdietzcanada.org\/fr\/wp-json\/wp\/v2\/media\/8757"}],"wp:attachment":[{"href":"https:\/\/loeysdietzcanada.org\/fr\/wp-json\/wp\/v2\/media?parent=8759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loeysdietzcanada.org\/fr\/wp-json\/wp\/v2\/categories?post=8759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loeysdietzcanada.org\/fr\/wp-json\/wp\/v2\/tags?post=8759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}